{"id":7671,"date":"2021-05-05T10:48:17","date_gmt":"2021-05-05T08:48:17","guid":{"rendered":"https:\/\/www.saintfrancoislongchamp.com\/titre\/se-faire-chouchouter-le-centre-de-balneotherapie-bien-etre\/bon-plan-balneo-1\/"},"modified":"2023-03-27T12:16:31","modified_gmt":"2023-03-27T10:16:31","slug":"bon-plan-balneo-1","status":"publish","type":"page","link":"https:\/\/www.saintfrancoislongchamp.com\/nl\/se-faire-chouchouter-le-centre-de-balneotherapie-bien-etre\/bon-plan-balneo-1\/","title":{"rendered":"Goed plan #1"},"content":{"rendered":"<section class=\"Annonce\">\n            <img decoding=\"async\" class=\"Annonce-picto svg\" data-skip-lazy=\"\" src=\"https:\/\/www.saintfrancoislongchamp.com\/content\/uploads\/2021\/05\/icons8-lotus-100.png\"\n             alt=\"Icone lotus bien-\u00eatre\"\/>\n        <div class=\"Annonce-content\">\n        Bij aankoop van een behandeling of modellering krijgt u 1 uur toegang tot de zwembaden van het Balneotherapiecentrum tegen een voorkeurtarief.\r\nSlechts 10 \u20ac per toegang (in plaats van 14 \u20ac). \r\n*De toegang tot de zwembaden moet worden gebruikt op de dag van de behandeling, voor of na de behandeling. \n    <\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":0,"parent":8489,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-7671","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.saintfrancoislongchamp.com\/nl\/wp-json\/wp\/v2\/pages\/7671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saintfrancoislongchamp.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.saintfrancoislongchamp.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.saintfrancoislongchamp.com\/nl\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saintfrancoislongchamp.com\/nl\/wp-json\/wp\/v2\/comments?post=7671"}],"version-history":[{"count":7,"href":"https:\/\/www.saintfrancoislongchamp.com\/nl\/wp-json\/wp\/v2\/pages\/7671\/revisions"}],"predecessor-version":[{"id":17743,"href":"https:\/\/www.saintfrancoislongchamp.com\/nl\/wp-json\/wp\/v2\/pages\/7671\/revisions\/17743"}],"up":[{"embeddable":true,"href":"https:\/\/www.saintfrancoislongchamp.com\/nl\/wp-json\/wp\/v2\/pages\/8489"}],"wp:attachment":[{"href":"https:\/\/www.saintfrancoislongchamp.com\/nl\/wp-json\/wp\/v2\/media?parent=7671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}